{"id":223,"date":"2026-03-19T02:15:42","date_gmt":"2026-03-19T02:15:42","guid":{"rendered":"https:\/\/escudodigital.uy\/index.php\/2026\/03\/19\/las-contrasenas-por-si-solas-no-son-suficientes\/"},"modified":"2026-03-19T02:15:42","modified_gmt":"2026-03-19T02:15:42","slug":"las-contrasenas-por-si-solas-no-son-suficientes","status":"publish","type":"post","link":"https:\/\/escudodigital.uy\/index.php\/2026\/03\/19\/las-contrasenas-por-si-solas-no-son-suficientes\/","title":{"rendered":"Las contrase\u00f1as por s\u00ed solas no son suficientes"},"content":{"rendered":"<div>\n<p class=\"sub-title\">Nunca conf\u00edes s\u00f3lo en una contrase\u00f1a, por muy segura que sea. La autenticaci\u00f3n multifactor es esencial para cualquiera que quiera proteger sus cuentas en l\u00ednea de intrusos.<\/p>\n<div class=\"article-authors d-flex flex-wrap\">\n<div class=\"article-author d-flex\"><picture><source srcset=\"https:\/\/web-assets.esetstatic.com\/tn\/-x45\/wls\/2013\/12\/pen-tip-200.png\" media=\"(max-width: 768px)\"\/><img decoding=\"async\" class=\"author-image me-3\" src=\"https:\/\/web-assets.esetstatic.com\/tn\/-x45\/wls\/2013\/12\/pen-tip-200.png\" alt=\"Editor\"\/><\/picture><\/div>\n<\/div>\n<p class=\"article-info mb-5\">\n        <span>08 de octubre de 2025<\/span>\n    <\/p>\n<\/div>\n<div>\n<p>Octubre es el Mes de la Concientizaci\u00f3n sobre la Ciberseguridad, un buen momento para hacer una pausa y reflexionar sobre c\u00f3mo proteger su mundo digital y sus cuentas en l\u00ednea en particular. Para muchas personas, esto sigue siendo s\u00f3lo una contrase\u00f1a.<\/p>\n<p>Pero aqu\u00ed est\u00e1 el problema: las contrase\u00f1as por s\u00ed solas no son suficientes para hacer frente a muchas de las ciberamenazas comunes de la actualidad. Esta primera l\u00ednea de defensa tradicional se ha debilitado peligrosamente a lo largo de los a\u00f1os, a medida que los ataques de phishing, las violaciones de datos y las filtraciones de credenciales hacen que sea m\u00e1s f\u00e1cil que nunca para los ciberdelincuentes ingresar a las cuentas en l\u00ednea de las personas, especialmente si sus propietarios reutilizan contrase\u00f1as iguales o similares en varias cuentas.<\/p>\n<p>Ah\u00ed es donde la autenticaci\u00f3n multifactor, o MFA, puede marcar la diferencia. Al agregar una segunda prueba de identidad, MFA puede detener a los atacantes en seco, incluso si han robado su contrase\u00f1a. Sin embargo, no todas las opciones de AMF son iguales. Si bien la MFA basada en SMS es mucho mejor que nada, opte por una aplicaci\u00f3n de autenticaci\u00f3n siempre que pueda, o incluso por una clave de seguridad de hardware.<\/p>\n<p>La misma urgencia se aplica a las empresas. Para organizaciones grandes y peque\u00f1as, s\u00f3lidas <a href=\"https:\/\/www.eset.com\/us\/business\/solutions\/multi-factor-authentication\/\" target=\"_blank\" rel=\"noopener\">Ministerio de Asuntos Exteriores<\/a> Es una l\u00ednea de defensa no negociable, ya que una autenticaci\u00f3n s\u00f3lida protege los sistemas, adem\u00e1s de salvaguardar la confianza, la propiedad intelectual y la reputaci\u00f3n del cliente.<\/p>\n<p>Por lo tanto, este octubre, adquiera el h\u00e1bito de habilitar MFA siempre que pueda y anime a sus equipos y colegas a hacer lo mismo. Adem\u00e1s, obtenga informaci\u00f3n sobre otras formas de autenticaci\u00f3n que son cada vez m\u00e1s comunes, como la autenticaci\u00f3n sin contrase\u00f1a, incluidas las claves de acceso.<\/p>\n<p>Mire el video con Tony Anscombe, evangelista jefe de seguridad de ESET, para obtener m\u00e1s informaci\u00f3n y permanezca atento a m\u00e1s videos para conmemorar el Mes de la Concientizaci\u00f3n sobre la Ciberseguridad, una campa\u00f1a celebrada a nivel mundial, incluso en los Estados Unidos. <a href=\"https:\/\/www.staysafeonline.org\/cybersecurity-awareness-month\">A NOSOTROS<\/a>, <a href=\"https:\/\/www.getcybersafe.gc.ca\/en\/cyber-security-awareness-month\">Canad\u00e1<\/a>, <a href=\"https:\/\/www.cyber.gov.au\/business-government\/cyber-security-awareness-month\" target=\"_blank\" rel=\"noopener\">Australia<\/a> y a trav\u00e9s <a href=\"https:\/\/cybersecuritymonth.eu\/about-ecsm\">Europa<\/a>.<\/p>\n<p>Adem\u00e1s, \u00bfpor qu\u00e9 no conocer m\u00e1s acerca de ESET? <a href=\"https:\/\/www.eset.com\/us\/business\/cybertraining\/\" target=\"_blank\" rel=\"noopener\">formaci\u00f3n de sensibilizaci\u00f3n en ciberseguridad<\/a>?<\/p>\n<p><iframe class=\"embed-video\" title=\"\" src=\"https:\/\/www.youtube-nocookie.com\/embed\/BFTQyK1HIYg\"><\/iframe><\/p>\n<blockquote>\n<p>Con\u00e9ctate con nosotros en <a href=\"https:\/\/www.facebook.com\/eset\">Facebook<\/a>, <a href=\"https:\/\/x.com\/ESET\" target=\"_blank\" rel=\"noopener\">inc\u00f3gnita<\/a>, <a href=\"https:\/\/www.linkedin.com\/company\/eset\/\">LinkedIn<\/a> y <a href=\"https:\/\/www.instagram.com\/eset\/\">Instagram<\/a>.<\/p>\n<\/blockquote>\n<\/div>\n<p><script async src=\"\/\/www.instagram.com\/embed.js\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nunca conf\u00edes s\u00f3lo en una contrase\u00f1a, por muy segura que sea. La autenticaci\u00f3n multifactor es esencial para cualquiera<\/p>\n","protected":false},"author":1,"featured_media":224,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-223","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-security"],"_links":{"self":[{"href":"https:\/\/escudodigital.uy\/index.php\/wp-json\/wp\/v2\/posts\/223","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/escudodigital.uy\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/escudodigital.uy\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/escudodigital.uy\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/escudodigital.uy\/index.php\/wp-json\/wp\/v2\/comments?post=223"}],"version-history":[{"count":0,"href":"https:\/\/escudodigital.uy\/index.php\/wp-json\/wp\/v2\/posts\/223\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/escudodigital.uy\/index.php\/wp-json\/wp\/v2\/media\/224"}],"wp:attachment":[{"href":"https:\/\/escudodigital.uy\/index.php\/wp-json\/wp\/v2\/media?parent=223"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/escudodigital.uy\/index.php\/wp-json\/wp\/v2\/categories?post=223"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/escudodigital.uy\/index.php\/wp-json\/wp\/v2\/tags?post=223"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}